{"id":10139,"date":"2020-01-10T11:08:00","date_gmt":"2020-01-10T11:08:00","guid":{"rendered":"https:\/\/expedia.blog.it.sandwave.dev\/stories\/?p=10139"},"modified":"2021-09-01T22:33:54","modified_gmt":"2021-09-01T22:33:54","slug":"hotel-coloniali-in-america-centro-meridionale","status":"publish","type":"post","link":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/","title":{"rendered":"Hotel coloniali in America centro-meridionale"},"content":{"rendered":"<p>&#8220;Quando spagnoli e portoghesi si lanciarono alla conquista delle Americhe esportarono nuovi stili coloniali destinati a lasciare numerose tracce nell&#8217;architettura locale, soprattutto per quanto riguarda edifici religiosi e amministrativi. E nonostante l&#8217;era coloniale sia finita da quasi 200 anni, molti di quegli edifici rimangono tuttora a testimonianza dell&#8217;influenza iberica sull&#8217;architettura delle principali citt\u00e0 della regione. Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi hotel coloniali in America centro-meridionale che hanno saputo trasformare antichi palazzi in esclusive strutture ricettive.<\/p>\n<p>### Hotel Museo Spa Casa Santo Domingo, Antigua, Guatemala<img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/199000\/199111.jpg\" alt=\"186320.jpg?1588002685\" \/><\/p>\n<p>Oltre a essere un&#8217;attrazione storica, l&#8217;<a href=\"https:\/\/www.expedia.it\/Antigua-Guatemala-Hotel-Hotel-Museo-Spa-Casa-Santo-Domingo.h1246555.Informazioni-Hotel\">Hotel Santo Domingo<\/a> \u00e8 un hotel cinque stelle e un museo situato a pochi minuti dal centro di una delle citt\u00e0 pi\u00f9 suggestive dell&#8217;ex Impero spagnolo. Ma non aspettatevi la tipica opulenza dello stile barocco; un tempo questo grazioso edificio ospitava un convento e conserva tuttora un fascino semplice e austero. Danneggiato nel 1773 in seguito a un terremoto, \u00e8 stato restaurato con estrema cura e oggi presenta una suggestiva struttura a graticcio con soffitti a volta in mattoni e una piscina all&#8217;aperto che esalta la bellezza dell&#8217;edificio in pietra viva.<\/p>\n<p>Per scoprire altre sistemazioni in citt\u00e0, visitate la pagina dedicata agli <a href=\"https:\/\/www.expedia.it\/Antigua-Guatemala-Hotel.d180589.Guida-Viaggi-Hotel\">hotel ad Antigua<\/a>.<\/p>\n<p>### Hotel Colonial, Ouro Preto, Brasile<img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/199000\/199112.jpg\" alt=\"186321.jpg?1588002685\" \/><\/p>\n<p>Fondata nel 1678, la citt\u00e0 di Ouro Preto (che in portoghese significa &#8220;oro nero&#8221;) si svilupp\u00f2 principalmente nel secolo successivo, fino a diventare il centro pi\u00f9 importante della corsa all&#8217;oro brasiliana. E anche se le miniere sono ormai chiuse da tempo, a testimonianza di quel periodo di grande abbondanza rimangono alcuni dei migliori esempi del barocco e del rococ\u00f2 brasiliani. Dalle numerose chiese alle antiche dimore coloniali perfettamente conservate, la citt\u00e0 vanta uno dei patrimoni architettonici pi\u00f9 importanti del paese. L&#8217;<a href=\"https:\/\/www.expedia.it\/Ouro-Preto-Hotel-Hotel-Colonial.h12994635.Informazioni-Hotel\">Hotel Colonial<\/a> \u00e8 ospitato all&#8217;interno di un signorile palazzo del XVIII secolo affacciato su una delle stradine acciottolate del centro storico e i suoi gentili proprietari sono veri esperti della storia locale. Se volete scoprire il ricco passato della citt\u00e0, questo \u00e8 sicuramente il luogo perfetto da cui iniziare.<\/p>\n<p>Per scoprire altre sistemazioni in citt\u00e0, visitate la pagina dedicata agli <a href=\"https:\/\/www.expedia.it\/Ouro-Preto-Hotel.d500206.Guida-Viaggi-Hotel\">hotel a Ouro Preto<\/a>.<\/p>\n<p>### Quinta Real Puebla, Puebla, Messico<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/199000\/199113.jpg\" alt=\"180220.jpg?1588002685\" \/>Il Messico era la provincia pi\u00f9 ricca dell&#8217;Impero spagnolo nonch\u00e9 il cuore della Nuova Spagna. Non sorprende, quindi, che le citt\u00e0 messicane vantino alcuni dei pi\u00f9 straordinari esempi di architettura coloniale. Fondata da un gruppo di coloni spagnoli, Puebla era un tempo la roccaforte del cattolicesimo e della tradizione. Oggi \u00e8 considerata una delle citt\u00e0 pi\u00f9 belle di tutto il Messico e si \u00e8 trasformata in un vivace centro per le arti e la vita notturna. All&#8217;interno di un magnifico edificio del XVI secolo, ex sede del Convento dell&#8217;Immacolata Concezione, <a href=\"https:\/\/www.expedia.it\/Puebla-Hotel-Quinta-Real-Puebla.h21438.Informazioni-Hotel\">Quinta Real Puebla<\/a> \u00e8 un hotel esclusivo che unisce il fascino della storia a un lusso squisitamente moderno.<\/p>\n<p>Per scoprire altre sistemazioni in citt\u00e0, visitate la pagina dedicata agli <a href=\"https:\/\/www.expedia.it\/Puebla-Hotel.d2738.Guida-Viaggi-Hotel\">hotel a Puebla<\/a>.<\/p>\n<p>### Hacienda Kaan Ac, Valladolid, Messico<img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/199000\/199114.jpg\" alt=\"186322.jpg?1588002685\" \/><\/p>\n<p>Nella nostra lista di hotel coloniali non poteva naturalmente mancare una tipica hacienda. Queste grandi tenute agricole furono un elemento fondamentale del periodo coloniale in Messico e <a href=\"https:\/\/www.expedia.it\/Chichen-Itza-Valladolid-Hotel-Hacienda-Kaan-Ac.h6416889.Informazioni-Hotel\">Kaan Ac<\/a>, che risale addirittura al XVI secolo, \u00e8 tra le pi\u00f9 antiche del paese. A 10 minuti in auto dal centro storico di Valladolid, la struttura si presenta come un&#8217;imponente fortezza in pietra circondata da un vasto terreno con tanto di cappella originale. All&#8217;interno della struttura potrete inoltre ammirare carrozze, armature e una collezione di antichi orologi a pendolo. La piscina all&#8217;aperto si fonde perfettamente con l&#8217;ambiente circostante per consentirvi di fare una nuotata rinfrescante senza rompere l&#8217;incantesimo di questo luogo dove il tempo sembra essersi fermato.<\/p>\n<p>Per scoprire altre sistemazioni in citt\u00e0, visitate la pagina dedicata agli <a href=\"https:\/\/www.expedia.it\/Chichen-Itza-Valladolid-Hotel.d6063022.Guida-Viaggi-Hotel\">hotel a Valladolid<\/a>.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale<\/p>\n","protected":false},"author":6,"featured_media":10142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[136],"tags":[23],"authors":[],"class_list":["post-10139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-architettura","tag-architecture","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hotel coloniali in America centro-meridionale | Explore by Expedia<\/title>\n<meta name=\"description\" content=\"Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hotel coloniali in America centro-meridionale\" \/>\n<meta property=\"og:description\" content=\"Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.it\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-10T11:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:33:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/197000\/197020-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/\",\"url\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/\",\"name\":\"Hotel coloniali in America centro-meridionale | Explore by Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/197020-share-image.jpg\",\"datePublished\":\"2020-01-10T11:08:00+00:00\",\"dateModified\":\"2021-09-01T22:33:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#primaryimage\",\"url\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/197020-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/197020-share-image.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.it\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Architettura\",\"item\":\"https:\/\/www.expedia.it\/stories\/architettura\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hotel coloniali in America centro-meridionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\",\"url\":\"https:\/\/www.expedia.it\/stories\/\",\"name\":\"Expedia.it\",\"description\":\"Il Tuo Viaggio Comincia Qui\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.it\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hotel coloniali in America centro-meridionale | Explore by Expedia","description":"Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/","og_locale":"en_US","og_type":"article","og_title":"Hotel coloniali in America centro-meridionale","og_description":"Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale","og_url":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/","og_site_name":"Expedia.it","article_published_time":"2020-01-10T11:08:00+00:00","article_modified_time":"2021-09-01T22:33:54+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/197000\/197020-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/","url":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/","name":"Hotel coloniali in America centro-meridionale | Explore by Expedia","isPartOf":{"@id":"https:\/\/www.expedia.it\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/197020-share-image.jpg","datePublished":"2020-01-10T11:08:00+00:00","dateModified":"2021-09-01T22:33:54+00:00","author":{"@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Dal Guatemala al Brasile, fate un tuffo nel passato scegliendo uno di questi splendidi hotel coloniali in America centro-meridionale","breadcrumb":{"@id":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#primaryimage","url":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/197020-share-image.jpg","contentUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/197020-share-image.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.it\/stories\/hotel-coloniali-in-america-centro-meridionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.it\/stories\/"},{"@type":"ListItem","position":2,"name":"Architettura","item":"https:\/\/www.expedia.it\/stories\/architettura\/"},{"@type":"ListItem","position":3,"name":"Hotel coloniali in America centro-meridionale"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.it\/stories\/#website","url":"https:\/\/www.expedia.it\/stories\/","name":"Expedia.it","description":"Il Tuo Viaggio Comincia Qui","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.it\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c89c0867307ea4026e6797b616f717994e19c3a2e08e92acc2ad7a7f0ba483e?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/10139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/comments?post=10139"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/10139\/revisions"}],"predecessor-version":[{"id":15206,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/10139\/revisions\/15206"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media\/10142"}],"wp:attachment":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media?parent=10139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/categories?post=10139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/tags?post=10139"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/authors?post=10139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}