{"id":4798,"date":"2017-02-16T11:29:00","date_gmt":"2017-02-16T11:29:00","guid":{"rendered":"https:\/\/expedia.blog.it.sandwave.dev\/stories\/?p=4798"},"modified":"2021-09-01T22:06:12","modified_gmt":"2021-09-01T22:06:12","slug":"cile-guida-al-deserto-di-atacama","status":"publish","type":"post","link":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/","title":{"rendered":"Cile: guida al Deserto di Atacama"},"content":{"rendered":"<p>&#8220;Pur essendo &#8220;uno dei deserti pi\u00f9 aridi del mondo&#8221;, il Deserto di Atacama offre un paesaggio straordinario sotto la volta di sconfinati cieli stellati.<\/p>\n<p>### 1. Perch\u00e9 visitare il Deserto di Atacama<\/p>\n<p>Paesaggi marziani quelli che si trovano nel <strong>nord del Cile<\/strong>, nel <strong>Deserto di Atacama<\/strong>, il luogo pi\u00f9 arido sulla terra: canyon scolpiti dall&#8217;erosione del vento, e grandi laghi salati, ne fanno il posto ideale per testare in simulazione i <em>rover<\/em> da mandare su <strong>Marte<\/strong>. \u00c8 questo il deserto cileno: quasi impossibile trovarvi qualcosa di verde, o qualcosa di vivo, ma sede di tre dei maggiori osservatori astronomici internazionali. Con un&#8217;altitudine che va dai 2400 metri agli oltre 4200 metri slm, in quest&#8217;area convergono infatti una serie di fattori che la rendono perfetta per l&#8217;osservazione del cielo e delle stelle: aria tersa, pochissime piogge, e quasi totale assenza di inquinamento luminoso. Il deserto cileno \u00e8 un paradiso anche per i fotografi, che puntino il loro obiettivo verso il cielo o verso la terra.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/92000\/92819.jpg\" alt=\"Il deserto pi\u00f9 arido della terra vede la comparsa di qualche nube tra gennaio e febbraio, e anche un po&#039; di pioggia con qualche fortuna - By Alessandro Caproni - (https:\/\/www.flickr.com\/photos\/weyes\/25948718422\/in\/album-72157637583810136\/), via Flikr\" \/><figcaption>Guida al Deserto di Atacama &#8211; Il deserto pi\u00f9 arido della terra vede la comparsa di qualche nube tra gennaio e febbraio, e anche un po&#8217; di pioggia con qualche fortuna &#8211; By Alessandro Caproni &#8211; <\/figcaption><\/figure>\n<p>### 2. Cosa vedere<\/p>\n<p>Da vedere assolutamente <strong>i telescopi dell&#8217;European Southern Observatory<\/strong>. Atmosfere lunari a <strong>Cerro Paranal<\/strong>, sede dell&#8217;European Southern Observatory: un tour di tre ore per uno dei migliori centri al mondo in fatto di telescopi e osservazioni astronomiche. Il tour comprende la visita all&#8217;hotel costruito per il team di scienziati del Paranal, firmato dallo studio di architettura <strong>Auer + Weber<\/strong> e presente nel film della saga di <strong>James Bond<\/strong>, <em>Quantum of Solace<\/em>.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/38000\/38261.jpg\" alt=\"La residenza di design per gli scienziati dell&#039;ESO nel Deserto di Atacama - By I. Werz-Rein -  \" \/><figcaption>Guida al Deserto di Atacama &#8211; La residenza di design per gli scienziati dell&#8217;ESO nel Deserto di Atacama &#8211; By I. Werz-Rein &#8211; <\/figcaption><\/figure>\n<p>La citt\u00e0 di <strong>San Pedro de Atacama<\/strong> si \u00e8 andata sviluppando rapidamente negli ultimi anni arricchendosi (forse anche troppo) di hotel, resort, ristoranti e servizi per i viaggiatori essendo il punto di accesso per visitare le meraviglie racchiuse nel Deserto di Atacama. Tuttavia l&#8217;atmosfera rimane rilassata, si pu\u00f2 approfittare di molti comfort, come connessioni wifi e ottimi cappuccini, e organizzare tour ed escursioni verso il deserto.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/38000\/38262.jpg\" alt=\"\" \/>.jpg)<figcaption>Guida al Deserto di Atacama &#8211; L&#8217;aria pura e il cielo terso sono perfetti per osservare le stelle, con i telescopi o a occhio nudo &#8211; By Alessandro Caproni &#8211; <\/figcaption><\/figure>\n<p>### 3. Escursioni nel deserto cileno<\/p>\n<p>La citt\u00e0 di <strong>San Pedro<\/strong> \u00e8 il punto di appoggio perfetto per partire alla scoperta del deserto cileno: con un&#8217;unica escursione in auto si possono raggiungere le formazioni rocciose scolpite dal vento che formano la <strong>Valle de la Luna<\/strong> e la <strong>Valle di Marte<\/strong> (detta anche <strong>Valle de la Muerte<\/strong>), entrambi punti suggestivi per ammirare lo spettacolo del tramonto sul Deserto di Atacama.<\/p>\n<p>Pi\u00f9 a sud, a circa un centinaio di chilometri, si trova la <strong>Reserva Nacional de Los Flamencos<\/strong> <strong>(Riserva Nazionale dei Fenicotteri)<\/strong> che ospita al suo interno due piccoli laghi, la <strong>Laguna Mi\u00f1iques<\/strong> e la <strong>Laguna Miscanti<\/strong>.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/38000\/38263.jpg\" alt=\"\" \/><figcaption>Guida al Deserto di Atacama &#8211; La Laguna Miscanti, uno dei piccoli laghi sulla Cordigliera del Sale<\/figcaption><\/figure>\n<p>Partendo con un tour in auto da San Pedro si pu\u00f2 approfittare lungo il percorso per visitare anche <strong>Toconao<\/strong> e <strong>Socaire<\/strong>, caratteristici villaggi di artigiani. Tornando poi indietro merita una sosta la <strong>Laguna Chaxa<\/strong> nel mezzo del <strong>Salar de Atacama<\/strong>, habitat di fenicotteri rosa.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/38000\/38264.jpg\" alt=\"\" \/><figcaption>Guida al Deserto di Atacama &#8211; Fenicotteri rosa sulla Laguna Chaxa nel Deserto di Atacama &#8211; By Caroline Fuhrmann (Own work) &#8211; <\/figcaption><\/figure>\n<p>A pochi chilometri da <strong>San Pedro de Atacama<\/strong> si trova la <strong>Aldea de Tulor<\/strong>, uno dei <strong>siti archeologici pi\u00f9 antichi del Cile<\/strong>, tra la Cordigliera del Sale e le distese di dune di sabbia. La Aldea (piccolo villaggio, in spagnolo) si compone di una serie di piccole costruzioni circolari di influenza precolombiana, collegate tra loro ed utilizzate per lo svolgimento di diverse attivit\u00e0 quotidiane.<\/p>\n<p>### 4. Quando andare<\/p>\n<p>Il tempo in questa regione tende ad essere quasi sempre secco e soleggiato, ma il periodo migliore per visitare il Deserto di Atacama e dintorni va <strong>da marzo a dicembre<\/strong>: tenete a mente per\u00f2 che ottobre-novembre e marzo-aprile sono i mesi con meno visitatori. Evitare i periodi di luna piena se si programma di osservare le stelle.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/38000\/38265.jpg\" alt=\"\" \/><figcaption>Guida al Deserto di Atacama &#8211; La terra come Marte: qui sono stati fatti gli esperimenti con i rover da mandare sul pianeta rosso<\/figcaption><\/figure>\n<p>### 5. Come arrivare<\/p>\n<p>L&#8217;aeroporto di riferimento \u00e8 quello di <strong>Santiago del Cile<\/strong> <strong>(Aeropuerto Internacional Arturo Merino Ben\u00ectez)<\/strong>, servito da numerose compagnie aeree con uno scalo intermedio: <strong>Air France<\/strong>, <strong>Iberia<\/strong> e <strong>Tam Linhas<\/strong>. Da Santiago si raggiungere poi <strong>Calama<\/strong> con un volo interno, da dove si pu\u00f2 arrivare a <strong>San Pedro de Atacama<\/strong> in auto o bus percorrendo un centinaio di chilometri.<\/p>\n<p><strong><a href=\"https:\/\/www.expedia.it\/explore\/deserti-caldi-e-freddi-i-15-piu-affascinanti-del-mondo\">LEGGI ANCHE: Deserti caldi e freddi: i 15 pi\u00f9 affascinanti del mondo!<\/a><\/strong><\/p>\n<p>#### Photo credit<\/p>\n<p>Foto di copertina: Il deserto pi\u00f9 arido della terra vede la comparsa di qualche nube tra gennaio e febbraio, e anche un po&#8217; di pioggia con qualche fortuna &#8211; By Alessandro Caproni &#8211;<\/p>\n<p><a href=\"https:\/\/www.expedia.it\/explore\/mongolia-guida-al-deserto-del-gobi\"><strong>LEGGI ANCHE: Mongolia: guida al deserto dei Gobi!<\/strong><\/a>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cile: guida al Deserto di Atacama<\/p>\n","protected":false},"author":6,"featured_media":4799,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[137],"tags":[32,92,9],"authors":[],"class_list":["post-4798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avventura","tag-adventure","tag-guide","tag-nature","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cile: guida al Deserto di Atacama<\/title>\n<meta name=\"description\" content=\"Cile: guida al Deserto di Atacama\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cile: guida al Deserto di Atacama\" \/>\n<meta property=\"og:description\" content=\"Cile: guida al Deserto di Atacama\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.it\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-16T11:29:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:06:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/15000\/15984-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/\",\"url\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/\",\"name\":\"Cile: guida al Deserto di Atacama\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/06\/15984-share-image.jpg\",\"datePublished\":\"2017-02-16T11:29:00+00:00\",\"dateModified\":\"2021-09-01T22:06:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Cile: guida al Deserto di Atacama\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#primaryimage\",\"url\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/06\/15984-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/06\/15984-share-image.jpg\",\"width\":1024,\"height\":738},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.it\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avventura\",\"item\":\"https:\/\/www.expedia.it\/stories\/avventura\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cile: guida al Deserto di Atacama\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\",\"url\":\"https:\/\/www.expedia.it\/stories\/\",\"name\":\"Expedia.it\",\"description\":\"Il Tuo Viaggio Comincia Qui\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.it\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cile: guida al Deserto di Atacama","description":"Cile: guida al Deserto di Atacama","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/","og_locale":"en_US","og_type":"article","og_title":"Cile: guida al Deserto di Atacama","og_description":"Cile: guida al Deserto di Atacama","og_url":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/","og_site_name":"Expedia.it","article_published_time":"2017-02-16T11:29:00+00:00","article_modified_time":"2021-09-01T22:06:12+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/15000\/15984-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/","url":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/","name":"Cile: guida al Deserto di Atacama","isPartOf":{"@id":"https:\/\/www.expedia.it\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/06\/15984-share-image.jpg","datePublished":"2017-02-16T11:29:00+00:00","dateModified":"2021-09-01T22:06:12+00:00","author":{"@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Cile: guida al Deserto di Atacama","breadcrumb":{"@id":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#primaryimage","url":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/06\/15984-share-image.jpg","contentUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/06\/15984-share-image.jpg","width":1024,"height":738},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.it\/stories\/cile-guida-al-deserto-di-atacama\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.it\/stories\/"},{"@type":"ListItem","position":2,"name":"Avventura","item":"https:\/\/www.expedia.it\/stories\/avventura\/"},{"@type":"ListItem","position":3,"name":"Cile: guida al Deserto di Atacama"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.it\/stories\/#website","url":"https:\/\/www.expedia.it\/stories\/","name":"Expedia.it","description":"Il Tuo Viaggio Comincia Qui","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.it\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/4798"}],"collection":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/comments?post=4798"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/4798\/revisions"}],"predecessor-version":[{"id":14115,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/4798\/revisions\/14115"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media\/4799"}],"wp:attachment":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media?parent=4798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/categories?post=4798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/tags?post=4798"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/authors?post=4798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}