{"id":7630,"date":"2017-02-14T01:57:00","date_gmt":"2017-02-14T01:57:00","guid":{"rendered":"https:\/\/expedia.blog.it.sandwave.dev\/stories\/?p=7630"},"modified":"2021-09-01T22:17:43","modified_gmt":"2021-09-01T22:17:43","slug":"tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida","status":"publish","type":"post","link":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/","title":{"rendered":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida"},"content":{"rendered":"<p>&#8220;Un tour dello Yucatan, in Messico, non pu\u00f2 prescindere dalla visita agli antichi siti Maya. Da Tulum a Chich\u00e9n Itz\u00e1, ecco cosa vedere nello Yucatan.<\/p>\n<p>Per scoprire lo stato messicano pi\u00f9 apprezzato dai turisti bisogna percorrere un tour che <strong>da Canc\u00fan scende a Merida<\/strong>, toccando alcuni dei pi\u00f9 celebri siti Maya. Ecco cosa vedere nello Yucatan, tra skyline moderni e citt\u00e0 coloniali, spiagge bellissime e siti archeologici.<\/p>\n<p><strong><a href=\"https:\/\/www.expedia.it\/g\/rg\/beach\">TROVA le migliori offerte di Expedia per una vacanza al mare!<\/a><\/strong><\/p>\n<p><a href=\"\">&lt;a href=&quot;https:\/\/www.google.com\/maps\/d\/embed?mid=1XOXycxuY1tBAycA12tZtsl-ejgw&quot;&gt;https:\/\/www.google.com\/maps\/d\/embed?mid=1XOXycxuY1tBAycA12tZtsl-ejgw&lt;\/a&gt;<\/a><\/p>\n<p>### Canc\u00fan, che la festa abbia inizio<\/p>\n<p>Grattacieli, alberghi, ristoranti e una moltitudine di negozi, mercati tradizionali, shopping mall. <strong>Canc\u00fan (1)<\/strong> ti accoglie cos\u00ec, con la sua <strong>doppia anima di<\/strong> <strong>citt\u00e0 storica e cosmopolita<\/strong>, dove \u00e8 pi\u00f9 facile sentire parlare inglese che spagnolo grazie alla forte presenza di <em>gringos<\/em> americani che l&#8217;hanno eletta a paradiso tropicale a portata d&#8217;aereo.<\/p>\n<p>Difficile resistere alla seduzione delle sue spiagge di sabbia corallina incorniciate da un <strong>mare che dal turchese sfuma nel verde smeraldo<\/strong>. Ma questa \u00e8 anche la capitale del divertimento notturno con cabaret, spettacoli, feste, balli, concentrati senza soluzione di continuit\u00e0 nei locali della Zona Hotelera: la sottile lingua di sabbia lunga 22 chilometri che separa una laguna dal Mar dei Caraibi, dove si raggruppa la maggior parte degli hotel.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/92000\/92845.jpg\" alt=\"Veduta di Cancun - Di Irving Huertas - Opera propria, CC BY-SA 3.0, https:\/\/commons.wikimedia.org\/w\/index.php?curid=31172922\" \/><figcaption><a href=\"https:\/\/commons.wikimedia.org\/w\/index.php?curid=31172922\">Veduta di Cancun &#8211; Di Irving Huertas &#8211; Opera propria, CC BY-SA 3.0, https:\/\/commons.wikimedia.org\/w\/index.php?curid=31172922<\/a><\/figcaption><\/figure>\n<p>### Lungo la Riviera Maya<\/p>\n<p>La tentazione \u00e8 irresistibile: noleggiare una macchina per &#8220;fuggire&#8221; sull&#8217;autostrada costiera 307 (Carretera Federal per i messicani) alla scoperta di lidi corallini, siti archeologici, parchi e resort per tutti i gusti e le tasche. La tappa d&#8217;obbligo \u00e8 <strong>Playa del Carmen (2)<\/strong>, un tempo villaggio di pescatori, oggi regina della costa come dimostra l&#8217;alta concentrazione di hotel e ristoranti a pochi metri dalla spiaggia.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/92000\/92846.jpg\" alt=\"Playa del Carmen - By Elelicht (Own work)  , via Wikimedia Commons\" \/><figcaption>Playa del Carmen &#8211; By Elelicht (Own work) , via Wikimedia Commons<\/figcaption><\/figure>\n<p>Ma lungo la celebre riviera messicana non si possono perdere neanche il parco tematico di <strong>Xcaret (3)<\/strong>, quello eco archeologico di <strong>Xel-H\u00e1<\/strong> <strong>(4)<\/strong> e <strong>i cenotes<\/strong> <strong>(5)<\/strong>, gli antichi pozzi dove \u00e8 possibile nuotare e fare immersioni nelle grotte sotterranee.<\/p>\n<p>La Carretera continua veloce ancora pi\u00f9 a sud, verso il confine con il Belize. Noi per\u00f2 ci fermiamo a <strong>Tulum (6)<\/strong>, l&#8217;unico sito maya in riva al mare, preziosa testimonianza di quello che \u00e8 stato un porto commerciale ben prima della conquista spagnola. I suoi templi costruiti a picco sulla scogliera sono una cartolina suggestiva, la quint&#8217;essenza di questo spicchio di Messico tropicale al profumo di storia.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/92000\/92847.jpg\" alt=\"Tulum, il tempio del Dio dei venti - By Martin Falbisoner (Own work)  , via Wikimedia Commons\" \/><figcaption>Tulum, il tempio del Dio dei venti &#8211; By Martin Falbisoner (Own work) , via Wikimedia Commons<\/figcaption><\/figure>\n<p>### Due perle archeologiche: da Cob\u00e1 a Chich\u00e9n Itz\u00e1<\/p>\n<p>Un breve viaggio nel cuore della giungla ti conduce a <strong>Cob\u00e1 (7), un&#8217;area archeologica fra le pi\u00f9 antiche<\/strong> ed estese di tutto lo Yucat\u00e1n, che ti seduce con i resti del campo dove anticamente si praticava il gioco della pelota e la vertiginosa verticalit\u00e0 della sua piramide di pietra grigia, il Nohoch Mul (IX-XII secolo d.C).<\/p>\n<p>Prima la ammiri dal basso, poi provi ad arrampicarti sapendo che lo sforzo dei quadricipiti, alle prese con gradini molto ripidi, pi\u00f9 alti che larghi, sar\u00e0 ricompensato dallo spettacolo che troverai una volta in cima, a 40 metri d&#8217;altezza. <strong>Da lass\u00f9 la vista \u00e8 incredibile<\/strong>, senza traccia di civilt\u00e0 a perdita d&#8217;occhio: solo natura, silenzio e il fascino ipnotico della foresta.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/35000\/35551.jpg\" alt=\"Il sito Maya di Coba - By EnglishDavid (Own work)  , via Wikimedia Commons\" \/><figcaption>Il sito Maya di Coba &#8211; By EnglishDavid (Own work) , via Wikimedia Commons<\/figcaption><\/figure>\n<p>### Chich\u00e9n Itz\u00e1, il sito pi\u00f9 importante<\/p>\n<p><strong>Il pi\u00f9 importante sito Maya (8)<\/strong> \u00e8 affollato gi\u00e0 al mattino presto. La citt\u00e0 protetta dall&#8217;Unesco, fondata nel VI secolo e ampliata fino all&#8217;XI secolo, \u00e8 infatti un luogo-culto, famoso in tutto il mondo. Una volta l\u00ec scoprirai templi decorati con bassorilievi di uomini e animali, il pi\u00f9 grande campo del mondo Maya per il gioco della pelota, il Cenote Sagrado (&#8220;sacro&#8221;) che, spiegano le guide, era sede di rituali e offerte votive.<\/p>\n<p>Ma <strong>la struttura pi\u00f9 importante \u00e8 il Castillo<\/strong>, o piramide di Kukulk\u00e1n, costruita in modo che sulla scalinata del lato settentrionale a ogni equinozio (il 21 marzo al tramonto) si ripetesse sempre lo stesso fenomeno: un gioco di luce e ombra disegna il corpo sinuoso di un rettile &#8211; simbolo del dio Kukulk\u00e1n &#8211; che scende verso terra, indicando il tempo della semina. \u00c8 il celebre calendario Maya inciso nella pietra.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/92000\/92848.jpg\" alt=\"Tempio dei Guerrieri - By Keith Pomakis (Own work)  , via Wikimedia Commons\" \/><figcaption>Tempio dei Guerrieri &#8211; By Keith Pomakis (Own work) , via Wikimedia Commons<\/figcaption><\/figure>\n<p>### Il fascino coloniale di M\u00e9rida<\/p>\n<p>&#8220;Vedi queste case, cos\u00ec belle e ricche di storia? Sono il ricordo dei tempi d&#8217;oro, quando nella nostra citt\u00e0 vivevano pi\u00f9 miliardari che in ogni altro paese del mondo&#8221;. Premessa: Jos\u00e9, la mia guida, \u00e8 un po&#8217; di parte quando mi mostra le architetture Liberty sparse fra le vie di <strong>M\u00e9rida (9)<\/strong>, <strong>capitale dello Yucat\u00e1n<\/strong> (M\u00e9rida e non Canc\u00fan, come pensano in molti). Per\u00f2 ha ragione nel raccontare che qui vivevano personaggi ricchissimi, visto che nei secoli passati le terre attorno alla citt\u00e0 erano coltivate a <em>henequ\u00e9n<\/em>, un tipo di agave che ai tempi era considerato una specie di oro verde.<\/p>\n<p>Grazie all&#8217;agave, M\u00e9rida si \u00e8 abbellita di piazze, negozi, palazzi e viali alberati come <strong>il Paseo de Montejo<\/strong>, che imita gli Champs-\u00c9lys\u00e9es di Parigi. La pianta a scacchiera del centro storico ti conduce inevitabilmente alla Plaza Grande, la tipica piazza coloniale incorniciata da un pot-pourri di monumenti da contemplare incantati: dalla Cattedrale di San Idelfonso, la pi\u00f9 antica del Paese, alla Casa de Montejo originaria del XVI secolo, questo \u00e8 un luogo da Sindrome di Stendhal.<\/p>\n<figure class='image' data-markdown='1'>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/92000\/92849.jpg\" alt=\"Merida Zocalo - By Elelicht (Own work)  , via Wikimedia Commons\" \/><figcaption>Merida Zocalo &#8211; By Elelicht (Own work) , via Wikimedia Commons<\/figcaption><\/figure>\n<p><a href=\"\">&lt;a href=&quot;https:\/\/www.youtube-nocookie.com\/watch?v=V1mmnQqq1gY&#039;&#093;&lt;br \/&gt;&lt;br \/&gt;&lt;br \/&gt;&lt;br \/&gt;&quot;&gt;https:\/\/www.youtube-nocookie.com\/watch?v=V1mmnQqq1gY<\/a><\/p>\n<p><\/a>#### Photo Credit<\/p>\n<p>Foto di copertina: Tulum visto dalla spiaggia &#8211; By Bj\u00f8rn Christian T\u00f8rrissen , via Wikimedia Commons&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida<\/p>\n","protected":false},"author":6,"featured_media":7632,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[83],"tags":[44],"authors":[],"class_list":["post-7630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-itinerari","tag-itineraries","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida<\/title>\n<meta name=\"description\" content=\"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida\" \/>\n<meta property=\"og:description\" content=\"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.it\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-14T01:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:17:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/17000\/17116-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/\",\"url\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/\",\"name\":\"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/17116-share-image.jpg\",\"datePublished\":\"2017-02-14T01:57:00+00:00\",\"dateModified\":\"2021-09-01T22:17:43+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#primaryimage\",\"url\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/17116-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/17116-share-image.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.it\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Itinerari\",\"item\":\"https:\/\/www.expedia.it\/stories\/itinerari\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\",\"url\":\"https:\/\/www.expedia.it\/stories\/\",\"name\":\"Expedia.it\",\"description\":\"Il Tuo Viaggio Comincia Qui\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.it\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida","description":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/","og_locale":"en_US","og_type":"article","og_title":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida","og_description":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida","og_url":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/","og_site_name":"Expedia.it","article_published_time":"2017-02-14T01:57:00+00:00","article_modified_time":"2021-09-01T22:17:43+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/17000\/17116-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/","url":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/","name":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida","isPartOf":{"@id":"https:\/\/www.expedia.it\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/17116-share-image.jpg","datePublished":"2017-02-14T01:57:00+00:00","dateModified":"2021-09-01T22:17:43+00:00","author":{"@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida","breadcrumb":{"@id":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#primaryimage","url":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/17116-share-image.jpg","contentUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/17116-share-image.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.it\/stories\/tour-yucatan-cosa-vedere-tra-riviera-maya-e-dintorni-da-cancun-a-merida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.it\/stories\/"},{"@type":"ListItem","position":2,"name":"Itinerari","item":"https:\/\/www.expedia.it\/stories\/itinerari\/"},{"@type":"ListItem","position":3,"name":"Tour Yucatan: cosa vedere tra Riviera Maya e dintorni, da Cancun a Merida"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.it\/stories\/#website","url":"https:\/\/www.expedia.it\/stories\/","name":"Expedia.it","description":"Il Tuo Viaggio Comincia Qui","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.it\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/7630"}],"collection":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/comments?post=7630"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/7630\/revisions"}],"predecessor-version":[{"id":14693,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/7630\/revisions\/14693"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media\/7632"}],"wp:attachment":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media?parent=7630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/categories?post=7630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/tags?post=7630"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/authors?post=7630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}