{"id":8521,"date":"2019-02-21T16:35:00","date_gmt":"2019-02-21T16:35:00","guid":{"rendered":"https:\/\/expedia.blog.it.sandwave.dev\/stories\/?p=8521"},"modified":"2021-09-01T22:27:45","modified_gmt":"2021-09-01T22:27:45","slug":"gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10","status":"publish","type":"post","link":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/","title":{"rendered":"Gallerie d&#8217;arte moderna e contemporanea a Berlino: la Top 10"},"content":{"rendered":"<p>&#8220;Berlino \u00e8 colma di storia recente e una certa riluttanza a guardare al passato la proietta inevitabilmente verso il futuro. Per questo nella capitale tedesca <strong>l&#8217;arte moderna e quella contemporanea<\/strong> occupano uno spazio importante nella struttura della citt\u00e0: gallerie di differente grandezza, dallo spazio di quartiere all&#8217;istituto pi\u00f9 grande, ospitano in ogni momento mostre e <strong>vernissage<\/strong> su artisti all&#8217;avanguardia o in rampa di lancio. Per chi vuole restare aggiornato sulle ultime tendenze nel mondo dell&#8217;arte, <strong>Berlino<\/strong> \u00e8 il luogo ideale da visitare.<\/p>\n<p>Ecco le dieci gallerie di arte moderna e contemporanea pi\u00f9 interessanti di Berlino!<\/p>\n<p>1. Hamburger Bahnhof<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>Punto di partenza per scoprire l&#8217;arte recente a Berlino \u00e8 la vecchia stazione del treno che collegava la capitale ad Amburgo. Qui, nell&#8217;area che ancora oggi mantiene il nome di &#8220;<strong>Stazione di Amburgo<\/strong>&#8220;, ha sede il <em>Museum f\u00fcr Gegenwart<\/em> dedicato all&#8217;arte contemporanea (l&#8217;arte moderna copre il periodo fra la fine dell&#8217;Ottocento e il 1960, quella contemporanea parte dagli anni Sessanta per arrivare al presente). Opere di Andy Warhol, Robert Rauschenberg e <strong>Cy Twombly<\/strong> spiccano fra la collezione di quadri, ma non mancano video arte e fotografia per un&#8217;immersione totale nel &#8220;museo del tempo presente&#8221;, ovvero la traduzione letterale del nome dell&#8217;edificio.<\/p>\n<p>2. Sammlung Boros<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p>L&#8217;eco della Seconda Guerra Mondiale si sente ancora in alcune aree di Berlino, ma l&#8217;intraprendenza di artisti e collezionisti ha saputo modificare anche questi tristi ricordi. Il museo Sammlung Boros dedicato all&#8217;arte contemporanea \u00e8 infatti ospitato in quello che era un <strong>bunker anti-bombe<\/strong> del 1943. I coniugi tedeschi Boros hanno trasformato il freddo edificio in uno spazio di cinque piani dedicato allo stile attuale con opere recenti di artisti da ogni parte del mondo. Una visita alla collezione pu\u00f2 essere prenotata online.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/181000\/181535.jpg\" alt=\"boros_berlino.jpg?1551258841\" \/><\/p>\n<p><em>Sammlung Boros &#8211; By J\u00f6rg Z\u00e4gel &#8211; Own work, CC BY-SA 3.0, <a href=\"https:\/\/commons.wikimedia.org\/w\/index.php?curid=9963604\">https:\/\/commons.wikimedia.org\/w\/index.php?curid=9963604<\/a><\/em><\/p>\n<p>3. Berggruen<br \/>&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>L&#8217;arte moderna a Berlino \u00e8 di casa al museo Berggruen. Situato nell&#8217;elegante quartiere <strong>Charlottenburg<\/strong>, lo spazio offre la possibilit\u00e0 di ammirare da vicino quadri di Paul Klee, Henri Matisse, <strong>Picasso<\/strong> nonch\u00e9 le sculture dell&#8217;italiano Alberto Giacometti. A pochi passi di distanza lo storico castello di Charlottenburg del 1713 per un assaggio di arte locale del passato.<\/p>\n<p>4 SR Contemporary Art<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>C&#8217;\u00e8 anche un tocco d&#8217;Italia nel mondo artistico berlinese: la galleria di arte contemporanea SR \u00e8 stata fondata dall&#8217;italiana Sabrina Raffaghello nel 2001. Tuttora propone esibizioni di arte e fotografia di <strong>artisti italiani<\/strong>, e non solo, in rampa di lancio. La diversit\u00e0 di Berlino e la sua apertura verso altre culture sono ben rappresentate da questo spazio, che merita una visita durante una sosta nella capitale.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/181000\/181536.jpg\" alt=\"sr_berlino.jpg?1551259455\" \/><\/p>\n<p><em>SR Contemporary art Berlino ( \u00a9SR)<\/em><\/p>\n<p>5. KINDL<br \/>&#8212;&#8212;&#8211;<\/p>\n<p>Quartiere &#8220;cool&#8221; per eccellenza, <strong>Neuk\u00f6lln<\/strong> dispone di vari spazi dedicati all&#8217;arte moderna e contemporanea a Berlino. Loophole, ricavato in un ex bordello, \u00e8 quasi un vero centro sociale e ospita concerti oltre ad esibizioni di arte contemporanea. Il meno caotico <strong>KINDL<\/strong> ha numerose opere di artisti tedeschi dell&#8217;era attuale per scoprire le correnti stilistiche della Germania recente. Lo stesso palazzo, elegantemente illuminato alla sera, \u00e8 un piacere per gli occhi.<\/p>\n<p>6. K\u00f6nig Gallerie<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong>Kreuzberg<\/strong> \u00e8 un altro quartiere alla moda della citt\u00e0 e ovviamente non mancano gallerie di arte contemporanea. Questa corrente ha negli ultimi anni dato molto risalto ai video e alle performance artistiche, due filoni spesso analizzati negli spazi di K\u00f6nig Gallerie. Pu\u00f2 capitare di vedere qui lavori di artisti destinati a farsi un nome negli anni a venire, come <strong>Norbert Bisky<\/strong> e Julian Rosefeldt. Una volta fuori, se volete restare &#8220;alla moda&#8221;, potete tentare di entrare nella discoteca pi\u00f9 famosa di Berlino, l&#8217;esclusivo Berghain.<\/p>\n<p>7. KW Institute<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Da venticinque anni luogo cardine dell&#8217;arte contemporanea a Berlino, il <strong>KW Institute<\/strong> \u00e8 una tappa immancabile per gli appassionati del genere. La capacit\u00e0 dei curatori di mantenersi al passo coi tempi rende il KW un esempio per gli altri spazi simili in Germania e altrove. Esibizioni di <strong>fotografia<\/strong> si alternano alle mostre di quadri, in un continuo rinnovamento simbolo perfetto dell&#8217;arte dei nostri tempi.<\/p>\n<p>8. C\/O Berlin<br \/>&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Le arti visive di oggi hanno la loro casa nella capitale tedesca nei locali di C\/O Berlin. Ormai luogo di culto per i fotografi locali, lo spazio \u00e8 degno di una visita per chi ama <strong>l&#8217;arte contemporanea<\/strong> e sta visitando Berlino. Nel weekend ci sono comodi tour guidati al prezzo di 5 euro.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/181000\/181537.jpg\" alt=\"C-O_Berlin.jpg?1551259583\" \/><\/p>\n<p><em>C\/O Berlino (CC BY SA 4.0, di Raimond Spekking)<\/em><\/p>\n<p>9. KB K\u00fcnstlerhaus Bethanien<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>Una delle gallerie d&#8217;arte contemporanea a Berlino maggiormente famose \u00e8 la KB: proprio qui <strong>Marina Abramovic<\/strong>, la pi\u00f9 nota <em>performance artist<\/em> degli ultimi anni, ha presentato i suoi primi lavori, iniziando a farsi un nome nel mondo della cultura. Tutt&#8217;oggi la galleria \u00e8 un centro d&#8217;interesse per scoprire le nuove correnti dei modi di esprimersi moderni.<\/p>\n<p>10. Blain Southern<br \/>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Bill Viola, Damien Hirst, Fujiko Nakaya: nomi conosciuti per chi \u00e8 un fan dell&#8217;arte di oggi, ma da scoprire per chi vuole avvicinarsi alle ultime trovate degli artisti di tutto il mondo. Proprio le opere di questi e altri creativi sono in esibizione nella galleria privata <strong>Blain Southern<\/strong>, che si trova nel vivace quartiere Sch\u00f6neberg dove si pu\u00f2 comodamente unire cultura e divertimento nelle stesse vie. Una particolarit\u00e0 comune a tutta Berlino.<\/p>\n<p>#### Photo Credit<\/p>\n<p>Foto di copertina: Hamburger Bahnhof, CC by 2.0, di Jason Paris, <a href=\"https:\/\/www.flickr.com\/photos\/jasonparis\/4294924856\/\">https:\/\/www.flickr.com\/photos\/jasonparis\/4294924856\/<\/a>&#8220;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le migliori 10 gallerie d&#8217;arte moderna e contemporanea a Berlino,  centro nevralgico delle avanguardie artistiche<\/p>\n","protected":false},"author":6,"featured_media":8522,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[88],"tags":[24,8],"authors":[],"class_list":["post-8521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","tag-art","tag-top-list","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gallerie d&#039;arte moderna e contemporanea a Berlino: la Top 10 | Explore by Expedia<\/title>\n<meta name=\"description\" content=\"Le migliori 10 gallerie d&#039;arte moderna e contemporanea a Berlino, centro nevralgico delle avanguardie artistiche\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gallerie d&#039;arte moderna e contemporanea a Berlino: la Top 10\" \/>\n<meta property=\"og:description\" content=\"Le migliori 10 gallerie d&#039;arte moderna e contemporanea a Berlino, centro nevralgico delle avanguardie artistiche\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/\" \/>\n<meta property=\"og:site_name\" content=\"Expedia.it\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-21T16:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-01T22:27:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/175000\/175188-share-image.jpg\" \/>\n<meta name=\"author\" content=\"Expedia Team\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expedia Team\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/\",\"url\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/\",\"name\":\"Gallerie d'arte moderna e contemporanea a Berlino: la Top 10 | Explore by Expedia\",\"isPartOf\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/175188-share-image.jpg\",\"datePublished\":\"2019-02-21T16:35:00+00:00\",\"dateModified\":\"2021-09-01T22:27:45+00:00\",\"author\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\"},\"description\":\"Le migliori 10 gallerie d'arte moderna e contemporanea a Berlino, centro nevralgico delle avanguardie artistiche\",\"breadcrumb\":{\"@id\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#primaryimage\",\"url\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/175188-share-image.jpg\",\"contentUrl\":\"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/175188-share-image.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Explore\",\"item\":\"https:\/\/www.expedia.it\/stories\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arte\",\"item\":\"https:\/\/www.expedia.it\/stories\/arte\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gallerie d&#8217;arte moderna e contemporanea a Berlino: la Top 10\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#website\",\"url\":\"https:\/\/www.expedia.it\/stories\/\",\"name\":\"Expedia.it\",\"description\":\"Il Tuo Viaggio Comincia Qui\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.expedia.it\/stories\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389\",\"name\":\"Expedia Team\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g\",\"caption\":\"Expedia Team\"},\"url\":\"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gallerie d'arte moderna e contemporanea a Berlino: la Top 10 | Explore by Expedia","description":"Le migliori 10 gallerie d'arte moderna e contemporanea a Berlino, centro nevralgico delle avanguardie artistiche","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/","og_locale":"en_US","og_type":"article","og_title":"Gallerie d'arte moderna e contemporanea a Berlino: la Top 10","og_description":"Le migliori 10 gallerie d'arte moderna e contemporanea a Berlino, centro nevralgico delle avanguardie artistiche","og_url":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/","og_site_name":"Expedia.it","article_published_time":"2019-02-21T16:35:00+00:00","article_modified_time":"2021-09-01T22:27:45+00:00","og_image":[{"url":"https:\/\/a.travel-assets.com\/findyours-php\/viewfinder\/images\/res40\/175000\/175188-share-image.jpg"}],"author":"Expedia Team","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Expedia Team","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/","url":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/","name":"Gallerie d'arte moderna e contemporanea a Berlino: la Top 10 | Explore by Expedia","isPartOf":{"@id":"https:\/\/www.expedia.it\/stories\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#primaryimage"},"image":{"@id":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#primaryimage"},"thumbnailUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/175188-share-image.jpg","datePublished":"2019-02-21T16:35:00+00:00","dateModified":"2021-09-01T22:27:45+00:00","author":{"@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389"},"description":"Le migliori 10 gallerie d'arte moderna e contemporanea a Berlino, centro nevralgico delle avanguardie artistiche","breadcrumb":{"@id":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#primaryimage","url":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/175188-share-image.jpg","contentUrl":"https:\/\/www.expedia.it\/stories\/wp-content\/uploads\/2021\/07\/175188-share-image.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.expedia.it\/stories\/gallerie-darte-moderna-e-contemporanea-a-berlino-la-top-10\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Explore","item":"https:\/\/www.expedia.it\/stories\/"},{"@type":"ListItem","position":2,"name":"Arte","item":"https:\/\/www.expedia.it\/stories\/arte\/"},{"@type":"ListItem","position":3,"name":"Gallerie d&#8217;arte moderna e contemporanea a Berlino: la Top 10"}]},{"@type":"WebSite","@id":"https:\/\/www.expedia.it\/stories\/#website","url":"https:\/\/www.expedia.it\/stories\/","name":"Expedia.it","description":"Il Tuo Viaggio Comincia Qui","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.expedia.it\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/7420ac2a0d206769c4bee055dd92a389","name":"Expedia Team","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.expedia.it\/stories\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/462d1c27805d4ef11d34ed16118fa530?s=96&d=mm&r=g","caption":"Expedia Team"},"url":"https:\/\/www.expedia.it\/stories\/author\/expedia-team\/"}]}},"_links":{"self":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/8521"}],"collection":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/comments?post=8521"}],"version-history":[{"count":2,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/8521\/revisions"}],"predecessor-version":[{"id":14861,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/posts\/8521\/revisions\/14861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media\/8522"}],"wp:attachment":[{"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/media?parent=8521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/categories?post=8521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/tags?post=8521"},{"taxonomy":"authors","embeddable":true,"href":"https:\/\/www.expedia.it\/stories\/wp-json\/wp\/v2\/authors?post=8521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}